{"id":418,"date":"2018-08-13T12:35:20","date_gmt":"2018-08-13T10:35:20","guid":{"rendered":"https:\/\/www.fitshop.es\/blog\/?p=418"},"modified":"2018-12-27T13:17:55","modified_gmt":"2018-12-27T12:17:55","slug":"slackline-diversion-en-la-cuerda-floja","status":"publish","type":"post","link":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/","title":{"rendered":"Slackline: \u00a1ad\u00e9ntrate en un mundo de diversi\u00f3n sobre la cuerda floja!"},"content":{"rendered":"<p><a name=\"more-7400\"><\/a>Cuando hace buen tiempo se ven por todas partes: \u00abSlackliners\u00bb. Vaya, personas de cualquier edad que se balancean ligeramente sobre una cuerda floja anclada a dos puntos de fijaci\u00f3n, y que por norma general suelen tener una buena figura. Esta disciplina deportiva relativamente joven, que se sit\u00faa entre el equilibrismo y el funambulismo, es un deporte en s\u00ed mismo. Aunque lo que parece pan comido, es sobre todo al principio un asunto bastante inestable. Con este post queremos facilitar la iniciaci\u00f3n al tema a los usuarios principiantes de la <a href=\"https:\/\/www.fitshop.es\/cuerda-floja\">Slackline o cuerda floja<\/a>. Y es que una vez que consigas mantenerte en pie sobre la cuerda, no querr\u00e1s bajar nunca\u2026<!--more--><\/p>\n<h2 class=\"western\">Slacklining: desde los comienzos hasta convertirse en tendencia de ocio<\/h2>\n<div id=\"attachment_7406\" style=\"width: 210px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7406\" class=\"wp-image-7406 size-medium\" title=\"Slackline\" src=\"http:\/\/www.sport-tiedje.de\/blog\/wp-content\/uploads\/2016\/05\/slackline-389414_960_720-200x300.jpg\" alt=\"Slackline\" width=\"200\" height=\"300\"><p id=\"caption-attachment-7406\" class=\"wp-caption-text\">Recomendado s\u00f3lo para expertos&#8230;<\/p><\/div>\n<p>Este joven deporte tiene su origen en la escalada. Lo cre\u00f3 un grupo de escaladores aficionados en los a\u00f1os 80 como alternativa para los d\u00edas de descanso y lluvia en el Parque Nacional de Yosemite. En los \u00faltimos a\u00f1os la cuerda floja se ha desarrollado fuera de la escena de la escalada como una disciplina deportiva independiente. En Europa, el escalador Heinz Zak cuenta como uno de los pioneros de la slackline. Con una difusi\u00f3n cada vez mayor y un inter\u00e9s medi\u00e1tico en aumento, cada vez son m\u00e1s las personas que sienten fascinaci\u00f3n por mantener el equilibrio sobre la cuerda floja.<\/p>\n<h2 class=\"western\">\u00abSlacklining\u00bb para j\u00f3venes y mayores: variado, m\u00f3vil, social<\/h2>\n<p>Es obvio por qu\u00e9 la slackline se ha puesto de moda en los \u00faltimos a\u00f1os. El deporte de equilibrio es tan variado como motivador, adem\u00e1s de poseer numerosas ventajas:<\/p>\n<ul>\n<li>La cuerda floja es un deporte para todo el mundo: la edad y las caracter\u00edsticas deportivas no juegan ning\u00fan papel relevante. Realmente cualquiera puede practicar con la slackline. Las slacklines son f\u00e1cil de usar y tambi\u00e9n las pueden montar sin problemas principiantes sin conocimientos previos.<\/li>\n<li>Lo bueno de este deporte es que no necesitas ning\u00fan equipamiento adicional para practicarlo, m\u00e1s all\u00e1 de la propia slackline. De hecho tendr\u00e1s una mejor sensaci\u00f3n de equilibrio si no llevas calzado. Si colocas la slackline entre dos \u00e1rboles, recomendamos el uso de un <a href=\"https:\/\/www.fitshop.es\/gibbon-slackline-treewear-gib-tl01\" target=\"_blank\" rel=\"noopener\">protector de \u00e1rboles<\/a>. Por aquello de respetar el medioambiente.<\/li>\n<li>La slackline es tan compacta cuando la enrollas, que te la podr\u00e1s llevar y colocar en cualquier lugar. Con una <a href=\"https:\/\/www.fitshop.es\/slackline-tools-frameline-set-10m-slt-0136\" target=\"_blank\" rel=\"noopener\">estructura para slackline<\/a> ser\u00e1s totalmente independiente con respecto al lugar.<\/li>\n<li>\u00a1Practicar con la cuerda floja nunca resulta aburrido! Funline, Trickline, Longline o Highline. Hasta ahora han surgido infinidad de variantes. Mediante la variaci\u00f3n de la longitud y altura, la slackline puede ajustarse a tus propios l\u00edmites de rendimiento. Gracias a sus cualidades din\u00e1micas, podr\u00e1s aprender nuevos trucos constantemente, colocar la slackline a distinta altura o tensarla m\u00e1s.<\/li>\n<li>La cuerda floja es un entrenamiento de equilibrio especialmente divertido. Y es que, adem\u00e1s de los aspectos deportivos y de la experiencia corporal adquirida, la actividad al aire libre y la diversi\u00f3n conjunta con los amigos cobra un protagonismo esencial.<\/li>\n<\/ul>\n<h2 class=\"western\">\u00bfQu\u00e9 se entrena con la slackline?<img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-7407 size-medium\" title=\"Entrenamiento con Slackline\" src=\"http:\/\/www.sport-tiedje.de\/blog\/wp-content\/uploads\/2016\/05\/leisure-719771_960_720-200x300.jpg\" alt=\"Entrenamiento con Slackline\" width=\"200\" height=\"300\"><\/h2>\n<p>La Slackline es un sencillo aparato deportivo con diversos efectos saludables y terap\u00e9uticos. Al balancearse en la slackline se activa en primer lugar el control del cuerpo. Este din\u00e1mico deporte de moda es una combinaci\u00f3n \u00fanica de equilibrio, coordinaci\u00f3n y concentraci\u00f3n. Se convierte as\u00ed en el entrenamiento adicional ideal para cualquier disciplina deportiva, en la que una buena sensaci\u00f3n de equilibrio sea importante (escalada, esqu\u00ed o surf). Al caminar sobre la cuerda tambi\u00e9n entrenar\u00e1s la musculatura profunda, y no s\u00f3lo las piernas y gl\u00fateos. Incluso se empieza a emplear la slackline en la fisioterapia y la terapia del movimiento.<\/p>\n<h2 class=\"western\">Caracter\u00edsticas especiales de la slackline<\/h2>\n<p>Al contrario que en el funambulismo, la slackline o \u00abcuerda floja\u00bb no se tensa demasiado, sino que se estira con el peso corporal del usuario y despu\u00e9s vuelve el\u00e1sticamente a su lugar. De esta forma tu postura corporal tiene que ajustarse continuamente al movimiento din\u00e1mico propio de la slackline. Y es precisamente eso lo que supone el reto del \u00abslacklining\u00bb. Hacer el pino, hacer juegos malabares, montar en monociclo o dar grandes saltos. Existen innumerables posibilidades para las que puedes emplear la slackline. As\u00ed surgen nuevas opciones y trucos cada vez, que pondr\u00e1n a prueba tus capacidades de equilibrio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7405 size-full\" title=\"Equilibrio en la Slackline\" src=\"http:\/\/www.sport-tiedje.de\/blog\/wp-content\/uploads\/2016\/05\/classicX13_action_d.jpg\" alt=\"Equilibrio en la Slackline\" width=\"586\" height=\"391\"><\/p>\n<h2 class=\"western\">Todo comienzo es dif\u00edcil\u2026<\/h2>\n<p>Hay que aceptarlo. Los pasos pivotantes sobre una cuerda pueden parecer mas sencillos de lo que realmente son, sobre todo en ojos de los principiantes. Sobre todo al principio, todo se mueve mucho y los primeros intentos sobre la slackline suelen terminar tras unos cent\u00edmetros en el suelo. Mantener el equilibrio es de hecho una capacidad que necesitamos constantemente en nuestra vida cotidiana. Pero hace tiempo que esto no es un motivo para tener que intentarlo una y otra vez. Al fin y al cabo, primero tienes que acostumbrarte a los tambaleantes movimientos. Te aseguramos que el \u00abslacklining\u00bb es un deporte extremadamente motivador, ya que los principiantes avanzan r\u00e1pidamente. Con cada nuevo intento, junto con nuestros consejos, te acercar\u00e1s un poco m\u00e1s al otro extremo de la cuerda.<\/p>\n<h3 class=\"western\">Consejos de Fitshop para los primeros intentos en la slackline<\/h3>\n<ul>\n<li>Comienza con una slackline de 35mm \u2013 50mm. El ancho de las bandas ofrece mayor seguridad de pisada y son menos flexibles. Adem\u00e1s, sobre bandas m\u00e1s anchas es m\u00e1s sencillo estabilizar las articulaciones de salto, lo que facilita el equilibrio.<\/li>\n<li>Presta atenci\u00f3n a que la superficie sobre la que practiques sea blanda, como c\u00e9sped o arena.<\/li>\n<li>Elige puntos de anclaje estables y seguros. Los \u00e1rboles deben tener un di\u00e1metro de al menos 40 cm. No olvides asegurar las carracas \ud83d\ude42<\/li>\n<li>Tensa la cuerda preferiblemente a menor altura y distancia. Para empezar una longitud de 6-8 metros, a la altura de las rodillas, es ideal. Esto facilita el subirse y la slackline no se estirar\u00e1 tanto.<\/li>\n<li>No te subas directamente en los puntos de anclaje, ya que ah\u00ed la slackline se comporta de manera totalmente distinta. Te resultar\u00e1 mucho m\u00e1s f\u00e1cil subirte a una distancia de 1-2 m del punto de anclaje.<\/li>\n<li>S\u00f3lo puede haber una persona subida en la slackline.<\/li>\n<li>La postura corporal correcta es como sigue: no tienes que mirar abajo hacia el suelo o a la slackline en movimiento, sino que debes fijar tu mirada en un punto fijo, al frente; los brazos se deben extender a la altura de los hombros a ambos lados y los pies tienen que estar uno tras otro sobre la cuerda, al igual que cuando caminas.<\/li>\n<li>Que no te de verg\u00fcenza pedir ayuda. Sobre todo al principio, no te sobrar\u00e1 una mano sobre la que apoyarte.<\/li>\n<li>Proponte objetivos realistas. Tu primera meta no deber\u00eda ser dar muchos pasos a mucha velocidad, sino sencillamente sostenerte de manera estable y controlada sobre la cuerda. Una vez que controles esto, cumplir\u00e1s el requisito indispensable para dar tus pasos de manera segura sobre la cuerda el\u00e1stica.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Cuando hace buen tiempo se ven por todas partes: \u00abSlackliners\u00bb. Vaya, personas de cualquier edad que se balancean ligeramente sobre una cuerda floja anclada a dos puntos de fijaci\u00f3n, y que por norma general suelen tener una buena figura. Esta disciplina deportiva relativamente joven, que se sit\u00faa entre el equilibrismo y el funambulismo, es un [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":431,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[54,126],"class_list":["post-418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-outdoor","tag-slackline"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Slackline: \u00a1ad\u00e9ntrate en un mundo de diversi\u00f3n sobre la cuerda floja! - El Blog de Fitshop<\/title>\n<meta name=\"description\" content=\"La slackline es un deporte relativamente joven, que se sit\u00faa entre el equilibrismo y el funambulismo. Y aunque parezca f\u00e1cil, aqu\u00ed van algunos consejos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slackline: \u00a1ad\u00e9ntrate en un mundo de diversi\u00f3n sobre la cuerda floja! - El Blog de Fitshop\" \/>\n<meta property=\"og:description\" content=\"La slackline es un deporte relativamente joven, que se sit\u00faa entre el equilibrismo y el funambulismo. Y aunque parezca f\u00e1cil, aqu\u00ed van algunos consejos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de Fitshop\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FitshopES\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-13T10:35:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-27T12:17:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fitshop.es\/blog\/wp-content\/uploads\/2018\/08\/53_Slackline-un-asunto-inestable-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maikel S\u00e1nchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FitshopES\" \/>\n<meta name=\"twitter:site\" content=\"@FitshopES\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maikel S\u00e1nchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/\"},\"author\":{\"name\":\"Maikel S\u00e1nchez\",\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/#\\\/schema\\\/person\\\/5c7793bfdb6624a29533936f28f40bf2\"},\"headline\":\"Slackline: \u00a1ad\u00e9ntrate en un mundo de diversi\u00f3n sobre la cuerda floja!\",\"datePublished\":\"2018-08-13T10:35:20+00:00\",\"dateModified\":\"2018-12-27T12:17:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/\"},\"wordCount\":1211,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/53_Slackline-un-asunto-inestable-1.jpg\",\"keywords\":[\"outdoor\",\"slackline\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/\",\"url\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/\",\"name\":\"Slackline: \u00a1ad\u00e9ntrate en un mundo de diversi\u00f3n sobre la cuerda floja! - El Blog de Fitshop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/53_Slackline-un-asunto-inestable-1.jpg\",\"datePublished\":\"2018-08-13T10:35:20+00:00\",\"dateModified\":\"2018-12-27T12:17:55+00:00\",\"description\":\"La slackline es un deporte relativamente joven, que se sit\u00faa entre el equilibrismo y el funambulismo. Y aunque parezca f\u00e1cil, aqu\u00ed van algunos consejos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/53_Slackline-un-asunto-inestable-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/53_Slackline-un-asunto-inestable-1.jpg\",\"width\":960,\"height\":640,\"caption\":\"Slackline-diversi\u00f3n en la cuerda floja\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/slackline-diversion-en-la-cuerda-floja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slackline: \u00a1ad\u00e9ntrate en un mundo de diversi\u00f3n sobre la cuerda floja!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/\",\"name\":\"El Blog de Fitshop\",\"description\":\"N\u00ba 1 en Europa para el Fitness dom\u00e9stico\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/#organization\",\"name\":\"Fitshop.es\",\"url\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo-fitshop.png\",\"contentUrl\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo-fitshop.png\",\"width\":1200,\"height\":630,\"caption\":\"Fitshop.es\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FitshopES\",\"https:\\\/\\\/x.com\\\/FitshopES\",\"https:\\\/\\\/www.instagram.com\\\/fitshop.es\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/fitshop-iberica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/#\\\/schema\\\/person\\\/5c7793bfdb6624a29533936f28f40bf2\",\"name\":\"Maikel S\u00e1nchez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/817938271b9cb32a2ee4c03c23c5e4e94da9c3c5bcc28eee9c9baf12a801d245?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/817938271b9cb32a2ee4c03c23c5e4e94da9c3c5bcc28eee9c9baf12a801d245?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/817938271b9cb32a2ee4c03c23c5e4e94da9c3c5bcc28eee9c9baf12a801d245?s=96&d=mm&r=g\",\"caption\":\"Maikel S\u00e1nchez\"},\"description\":\"Maikel S\u00e1nchez es traductor y representante de atenci\u00f3n al cliente en Fitshop. Apasionado del senderismo y la monta\u00f1a, combina su experiencia profesional con su pasi\u00f3n por el fitness. Le gusta entrenar con una mezcla de fuerza y cardio.\",\"url\":\"https:\\\/\\\/www.fitshop.es\\\/blog\\\/author\\\/maikel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Slackline: \u00a1ad\u00e9ntrate en un mundo de diversi\u00f3n sobre la cuerda floja! - El Blog de Fitshop","description":"La slackline es un deporte relativamente joven, que se sit\u00faa entre el equilibrismo y el funambulismo. Y aunque parezca f\u00e1cil, aqu\u00ed van algunos consejos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/","og_locale":"es_ES","og_type":"article","og_title":"Slackline: \u00a1ad\u00e9ntrate en un mundo de diversi\u00f3n sobre la cuerda floja! - El Blog de Fitshop","og_description":"La slackline es un deporte relativamente joven, que se sit\u00faa entre el equilibrismo y el funambulismo. Y aunque parezca f\u00e1cil, aqu\u00ed van algunos consejos.","og_url":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/","og_site_name":"El Blog de Fitshop","article_publisher":"https:\/\/www.facebook.com\/FitshopES","article_published_time":"2018-08-13T10:35:20+00:00","article_modified_time":"2018-12-27T12:17:55+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.fitshop.es\/blog\/wp-content\/uploads\/2018\/08\/53_Slackline-un-asunto-inestable-1.jpg","type":"image\/jpeg"}],"author":"Maikel S\u00e1nchez","twitter_card":"summary_large_image","twitter_creator":"@FitshopES","twitter_site":"@FitshopES","twitter_misc":{"Escrito por":"Maikel S\u00e1nchez","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/#article","isPartOf":{"@id":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/"},"author":{"name":"Maikel S\u00e1nchez","@id":"https:\/\/www.fitshop.es\/blog\/#\/schema\/person\/5c7793bfdb6624a29533936f28f40bf2"},"headline":"Slackline: \u00a1ad\u00e9ntrate en un mundo de diversi\u00f3n sobre la cuerda floja!","datePublished":"2018-08-13T10:35:20+00:00","dateModified":"2018-12-27T12:17:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/"},"wordCount":1211,"commentCount":0,"publisher":{"@id":"https:\/\/www.fitshop.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fitshop.es\/blog\/wp-content\/uploads\/2018\/08\/53_Slackline-un-asunto-inestable-1.jpg","keywords":["outdoor","slackline"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/","url":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/","name":"Slackline: \u00a1ad\u00e9ntrate en un mundo de diversi\u00f3n sobre la cuerda floja! - El Blog de Fitshop","isPartOf":{"@id":"https:\/\/www.fitshop.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/#primaryimage"},"image":{"@id":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fitshop.es\/blog\/wp-content\/uploads\/2018\/08\/53_Slackline-un-asunto-inestable-1.jpg","datePublished":"2018-08-13T10:35:20+00:00","dateModified":"2018-12-27T12:17:55+00:00","description":"La slackline es un deporte relativamente joven, que se sit\u00faa entre el equilibrismo y el funambulismo. Y aunque parezca f\u00e1cil, aqu\u00ed van algunos consejos.","breadcrumb":{"@id":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/#primaryimage","url":"https:\/\/www.fitshop.es\/blog\/wp-content\/uploads\/2018\/08\/53_Slackline-un-asunto-inestable-1.jpg","contentUrl":"https:\/\/www.fitshop.es\/blog\/wp-content\/uploads\/2018\/08\/53_Slackline-un-asunto-inestable-1.jpg","width":960,"height":640,"caption":"Slackline-diversi\u00f3n en la cuerda floja"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fitshop.es\/blog\/slackline-diversion-en-la-cuerda-floja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fitshop.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Slackline: \u00a1ad\u00e9ntrate en un mundo de diversi\u00f3n sobre la cuerda floja!"}]},{"@type":"WebSite","@id":"https:\/\/www.fitshop.es\/blog\/#website","url":"https:\/\/www.fitshop.es\/blog\/","name":"El Blog de Fitshop","description":"N\u00ba 1 en Europa para el Fitness dom\u00e9stico","publisher":{"@id":"https:\/\/www.fitshop.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fitshop.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.fitshop.es\/blog\/#organization","name":"Fitshop.es","url":"https:\/\/www.fitshop.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fitshop.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.fitshop.es\/blog\/wp-content\/uploads\/2023\/05\/logo-fitshop.png","contentUrl":"https:\/\/www.fitshop.es\/blog\/wp-content\/uploads\/2023\/05\/logo-fitshop.png","width":1200,"height":630,"caption":"Fitshop.es"},"image":{"@id":"https:\/\/www.fitshop.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FitshopES","https:\/\/x.com\/FitshopES","https:\/\/www.instagram.com\/fitshop.es","https:\/\/www.linkedin.com\/showcase\/fitshop-iberica"]},{"@type":"Person","@id":"https:\/\/www.fitshop.es\/blog\/#\/schema\/person\/5c7793bfdb6624a29533936f28f40bf2","name":"Maikel S\u00e1nchez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/817938271b9cb32a2ee4c03c23c5e4e94da9c3c5bcc28eee9c9baf12a801d245?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/817938271b9cb32a2ee4c03c23c5e4e94da9c3c5bcc28eee9c9baf12a801d245?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/817938271b9cb32a2ee4c03c23c5e4e94da9c3c5bcc28eee9c9baf12a801d245?s=96&d=mm&r=g","caption":"Maikel S\u00e1nchez"},"description":"Maikel S\u00e1nchez es traductor y representante de atenci\u00f3n al cliente en Fitshop. Apasionado del senderismo y la monta\u00f1a, combina su experiencia profesional con su pasi\u00f3n por el fitness. Le gusta entrenar con una mezcla de fuerza y cardio.","url":"https:\/\/www.fitshop.es\/blog\/author\/maikel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fitshop.es\/blog\/wp-json\/wp\/v2\/posts\/418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fitshop.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fitshop.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fitshop.es\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fitshop.es\/blog\/wp-json\/wp\/v2\/comments?post=418"}],"version-history":[{"count":10,"href":"https:\/\/www.fitshop.es\/blog\/wp-json\/wp\/v2\/posts\/418\/revisions"}],"predecessor-version":[{"id":918,"href":"https:\/\/www.fitshop.es\/blog\/wp-json\/wp\/v2\/posts\/418\/revisions\/918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fitshop.es\/blog\/wp-json\/wp\/v2\/media\/431"}],"wp:attachment":[{"href":"https:\/\/www.fitshop.es\/blog\/wp-json\/wp\/v2\/media?parent=418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fitshop.es\/blog\/wp-json\/wp\/v2\/categories?post=418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fitshop.es\/blog\/wp-json\/wp\/v2\/tags?post=418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}